{"id":2526,"date":"2022-05-11T15:27:21","date_gmt":"2022-05-11T15:27:21","guid":{"rendered":"https:\/\/www.theconservative.online\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa"},"modified":"2022-05-12T16:59:59","modified_gmt":"2022-05-12T16:59:59","slug":"desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa","status":"publish","type":"post","link":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa","title":{"rendered":"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa"},"content":{"rendered":"<p>En una serie de art\u00edculos, planeo profundizar en la encuesta sobre las percepciones de la UE encargada por el Partido ECR, cuyos resultados generales se han resumido previamente <a href=\"https:\/\/www.ecrparty.eu\/files\/ECR_Europe_perception_from_Europeans_%281%29_%281%29.pdf\">aqu\u00ed<\/a> .<\/p>\n<p>A menudo se informa que los conservadores son gen\u00e9ricamente esc\u00e9pticos cuando se trata de Europa. Su conciencia del inter\u00e9s nacional se percibe como una barrera para cualquier construcci\u00f3n europea. Y, sin embargo, como deja en claro esta encuesta, la realidad es bastante diferente. La idea de Europa de los conservadores est\u00e1 mucho m\u00e1s articulada de lo que a veces se representa.<\/p>\n<p>Lo que surge de la encuesta es que los conservadores exhiben puntos de vista de varios niveles sobre Europa que no se prestan a una descripci\u00f3n simplista. Los entrevistados, cuando fueron presionados, encontraron puntos fuertes en el modelo europeo; asimismo, subrayaron la frustraci\u00f3n relacionada con pol\u00edticas espec\u00edficas vigentes. Esto sugiere que las opiniones conservadoras dependen de las pol\u00edticas.<\/p>\n<p>No sorprende, entonces, que la mayor\u00eda de los encuestados (52 por ciento) reconozca sentirse orgulloso de ser europeo, mientras que poco m\u00e1s de un tercio (35 por ciento) admita sentimientos negativos. En el primer caso, cuando se les pide que expliquen sus puntos de vista positivos, los simpatizantes de ECR (44 por ciento) enfatizan abrumadoramente las conexiones econ\u00f3micas y culturales entre pa\u00edses, mucho m\u00e1s que sus contrapartes que no son simpatizantes de ECR (41 por ciento versus 33 por ciento de los no simpatizantes). simpatizantes de la ECR).<\/p>\n<p>Adem\u00e1s, los simpatizantes de ECR con una visi\u00f3n positiva de Europa enfatizan las oportunidades econ\u00f3micas que ofrece Europa en t\u00e9rminos de vivir y trabajar en otro pa\u00eds, aunque en menor grado que los simpatizantes que no son de ECR (38 por ciento frente a 45). Los simpatizantes de ECR tambi\u00e9n aprecian la igualdad de trato, incluida la protecci\u00f3n de las normas laborales, a la que tienen derecho. Otros aspectos que elogian incluyen los beneficios del Mercado \u00danico, incluida la posibilidad de vender bienes y servicios y la disponibilidad de financiaci\u00f3n de infraestructuras.<\/p>\n<p>Es igualmente esclarecedor examinar las respuestas de aquellos que expresaron sentimientos negativos hacia Europa, de los cuales los simpatizantes de ECR representaron casi la mitad. Cuando se les pidi\u00f3 que se explicaran, los simpatizantes de ECR se\u00f1alaron el exceso de tr\u00e1mites burocr\u00e1ticos (38 por ciento frente al 29 por ciento entre los no simpatizantes de ECR), el temor de que los pa\u00edses individuales pierdan su identidad cultural (37 por ciento frente a 24) y el aumento de delincuencia resultante de la apertura de fronteras (23 por ciento y 16 por ciento, respectivamente).<\/p>\n<p>En otras palabras, los conservadores aprecian los beneficios de un lugar m\u00e1s amplio que conecta a las sociedades europeas y las oportunidades culturales y econ\u00f3micas que surgen de ello. Sin embargo, tienden a desconfiar de cualquier conexi\u00f3n que diluya sus identidades culturales \u00fanicas o imponga cargas regulatorias y administrativas excesivas, un recelo que nace de prioridades mejor definidas.<\/p>\n<p>Un cuadro muy similar surge con respecto a la confianza en la Uni\u00f3n Europea como instituci\u00f3n. Entre los encuestados que sintieron \u00abmucha\u00bb o \u00abbastante\u00bb confianza (45 por ciento), los simpatizantes de ECR representan alrededor del 43 por ciento, una parte significativa, si no la mayor\u00eda. Entre los que informan una actitud negativa hacia Europa (41 por ciento), los simpatizantes de ECR est\u00e1n en mayor proporci\u00f3n (50 por ciento), lo que probablemente refleja una percepci\u00f3n negativa de la burocracia de la UE tal como existe hoy.<\/p>\n<p>Sin embargo, esto no quiere decir que los conservadores se opongan a la idea de Europa per se; m\u00e1s bien, prev\u00e9n diferentes prioridades y pol\u00edticas europeas, m\u00e1s acordes con las necesidades e intereses del ciudadano europeo medio. Para los conservadores, estas prioridades deben sentar las bases para el debate sobre la reforma europea.<\/p>\n<p><em>domenico lombardi<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una serie de art\u00edculos, planeo profundizar en la encuesta sobre las percepciones de la UE encargada por el Partido ECR, cuyos resultados generales se han resumido previamente aqu\u00ed . A menudo se informa que los conservadores son gen\u00e9ricamente esc\u00e9pticos cuando se trata de Europa. Su conciencia del inter\u00e9s nacional se percibe como una barrera [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":2190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[179,165],"tags":[],"editorial-positions":[],"regions":[327,337,348,357,363],"types":[],"class_list":["post-2526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ensayos","category-politica-es","regions-central-europe-es","regions-eastern-europe-es","regions-northern-europe-es","regions-southern-europe-es","regions-western-europe-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa - The Conservative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa - The Conservative\" \/>\n<meta property=\"og:description\" content=\"En una serie de art\u00edculos, planeo profundizar en la encuesta sobre las percepciones de la UE encargada por el Partido ECR, cuyos resultados generales se han resumido previamente aqu\u00ed . A menudo se informa que los conservadores son gen\u00e9ricamente esc\u00e9pticos cuando se trata de Europa. Su conciencia del inter\u00e9s nacional se percibe como una barrera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\" \/>\n<meta property=\"og:site_name\" content=\"The Conservative\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T15:27:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T16:59:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"theconservative\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"theconservative\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\"},\"author\":{\"name\":\"theconservative\",\"@id\":\"https:\/\/www.theconservative.online\/es#\/schema\/person\/5e21e1987b64e214571052e6c09d979a\"},\"headline\":\"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa\",\"datePublished\":\"2022-05-11T15:27:21+00:00\",\"dateModified\":\"2022-05-12T16:59:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\"},\"wordCount\":654,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg\",\"articleSection\":[\"Ensayos\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\",\"url\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\",\"name\":\"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa - The Conservative\",\"isPartOf\":{\"@id\":\"https:\/\/www.theconservative.online\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg\",\"datePublished\":\"2022-05-11T15:27:21+00:00\",\"dateModified\":\"2022-05-12T16:59:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.theconservative.online\/es#\/schema\/person\/5e21e1987b64e214571052e6c09d979a\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage\",\"url\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg\",\"contentUrl\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg\",\"width\":750,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.theconservative.online\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.theconservative.online\/es#website\",\"url\":\"https:\/\/www.theconservative.online\/es\",\"name\":\"The Conservative\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.theconservative.online\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.theconservative.online\/es#\/schema\/person\/5e21e1987b64e214571052e6c09d979a\",\"name\":\"theconservative\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.theconservative.online\/es#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/90f167a23521a1404cf9890ae77f194024ab1f0ec3639b04021c3478e7d7f737?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/90f167a23521a1404cf9890ae77f194024ab1f0ec3639b04021c3478e7d7f737?s=96&d=mm&r=g\",\"caption\":\"theconservative\"},\"url\":\"https:\/\/www.theconservative.online\/es\/author\/theconservative-admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa - The Conservative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa","og_locale":"es_ES","og_type":"article","og_title":"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa - The Conservative","og_description":"En una serie de art\u00edculos, planeo profundizar en la encuesta sobre las percepciones de la UE encargada por el Partido ECR, cuyos resultados generales se han resumido previamente aqu\u00ed . A menudo se informa que los conservadores son gen\u00e9ricamente esc\u00e9pticos cuando se trata de Europa. Su conciencia del inter\u00e9s nacional se percibe como una barrera [&hellip;]","og_url":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa","og_site_name":"The Conservative","article_published_time":"2022-05-11T15:27:21+00:00","article_modified_time":"2022-05-12T16:59:59+00:00","og_image":[{"width":750,"height":375,"url":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg","type":"image\/jpeg"}],"author":"theconservative","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"theconservative","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#article","isPartOf":{"@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa"},"author":{"name":"theconservative","@id":"https:\/\/www.theconservative.online\/es#\/schema\/person\/5e21e1987b64e214571052e6c09d979a"},"headline":"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa","datePublished":"2022-05-11T15:27:21+00:00","dateModified":"2022-05-12T16:59:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa"},"wordCount":654,"commentCount":0,"image":{"@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage"},"thumbnailUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg","articleSection":["Ensayos","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa","url":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa","name":"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa - The Conservative","isPartOf":{"@id":"https:\/\/www.theconservative.online\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage"},"image":{"@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage"},"thumbnailUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg","datePublished":"2022-05-11T15:27:21+00:00","dateModified":"2022-05-12T16:59:59+00:00","author":{"@id":"https:\/\/www.theconservative.online\/es#\/schema\/person\/5e21e1987b64e214571052e6c09d979a"},"breadcrumb":{"@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#primaryimage","url":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg","contentUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2022\/05\/1604_editorial_2.jpeg","width":750,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.theconservative.online\/es\/desacreditando-los-mitos-sobre-los-conservadores-percepciones-en-y-alrededor-de-europa#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theconservative.online\/es"},{"@type":"ListItem","position":2,"name":"Desacreditando los mitos sobre los conservadores: percepciones en y alrededor de Europa"}]},{"@type":"WebSite","@id":"https:\/\/www.theconservative.online\/es#website","url":"https:\/\/www.theconservative.online\/es","name":"The Conservative","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theconservative.online\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.theconservative.online\/es#\/schema\/person\/5e21e1987b64e214571052e6c09d979a","name":"theconservative","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.theconservative.online\/es#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/90f167a23521a1404cf9890ae77f194024ab1f0ec3639b04021c3478e7d7f737?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/90f167a23521a1404cf9890ae77f194024ab1f0ec3639b04021c3478e7d7f737?s=96&d=mm&r=g","caption":"theconservative"},"url":"https:\/\/www.theconservative.online\/es\/author\/theconservative-admin"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/posts\/2526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/comments?post=2526"}],"version-history":[{"count":1,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/posts\/2526\/revisions"}],"predecessor-version":[{"id":2532,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/posts\/2526\/revisions\/2532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/media\/2190"}],"wp:attachment":[{"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/media?parent=2526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/categories?post=2526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/tags?post=2526"},{"taxonomy":"editorial-positions","embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/editorial-positions?post=2526"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/regions?post=2526"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.theconservative.online\/es\/wp-json\/wp\/v2\/types?post=2526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}