{"id":51651,"date":"2026-02-28T19:09:35","date_gmt":"2026-02-28T19:09:35","guid":{"rendered":"https:\/\/www.theconservative.online\/un-monde-de-petites-cours-et-de-hautes-clotures-non"},"modified":"2026-02-28T19:09:35","modified_gmt":"2026-02-28T19:09:35","slug":"un-monde-de-petites-cours-et-de-hautes-clotures-non","status":"publish","type":"post","link":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non","title":{"rendered":"Un monde de petites cours et de hautes cl\u00f4tures ? Non !"},"content":{"rendered":"<p style=\"font-weight: 400;\">S&rsquo;il est un principe sur lequel tous les \u00e9tudiants s\u00e9rieux en \u00e9conomie s&rsquo;accordent, c&rsquo;est bien celui du libre-\u00e9change. La division du travail entre les individus et les pays augmente le produit total, car les gens font alors ce qu&rsquo;ils savent faire le mieux, et ils en profitent, ainsi que les autres. Nous ne devons cependant pas ignorer l&rsquo;opposition persistante au libre-\u00e9change. Le protectionnisme n&rsquo;est pas une lubie personnelle du pr\u00e9sident am\u00e9ricain Donald Trump. Il a \u00e9t\u00e9 la r\u00e8gle plut\u00f4t que l&rsquo;exception dans l&rsquo;histoire des \u00c9tats-Unis, et il jouit d&rsquo;un solide soutien ailleurs. Il ne peut pas \u00eatre simplement rejet\u00e9 avec d\u00e9dain. Au contraire, il convient de la comprendre et d&rsquo;y r\u00e9pondre par ce que j&rsquo;appellerais les AA : Arguments et Alliances.      <\/p>\n<h3 style=\"font-weight: 400;\">Le soutien au protectionnisme<\/h3>\n<p style=\"font-weight: 400;\">Deux faits expliquent l&rsquo;attrait politique du protectionnisme. Le premier est la r\u00e9partition in\u00e9gale des b\u00e9n\u00e9fices et des pertes du libre-\u00e9change. Les avantages sont dispers\u00e9s, tandis que les pertes sont concentr\u00e9es. Les avantages &#8211; baisse des prix et renforcement de la concurrence &#8211; ne deviennent visibles qu&rsquo;\u00e0 long terme et profitent \u00e0 l&rsquo;ensemble de la population, ce qui signifie que le b\u00e9n\u00e9fice pour chaque citoyen n&rsquo;est pas tr\u00e8s important \u00e0 un moment donn\u00e9. Les pertes du libre-\u00e9change, telles que la disparition d&#8217;emplois improductifs, sont en revanche clairement visibles \u00e0 court terme. De plus, ces pertes ne touchent qu&rsquo;une petite partie de la population, qui en est donc bien consciente. L&rsquo;ensemble de la population profite de la baisse des prix des denr\u00e9es alimentaires, si celles-ci sont \u00e9chang\u00e9es librement, mais seuls les producteurs de denr\u00e9es alimentaires, les agriculteurs, b\u00e9n\u00e9ficient de la protection contre la concurrence \u00e9trang\u00e8re. Ceux qui se consid\u00e8rent comme les perdants du libre-\u00e9change sont incit\u00e9s \u00e0 organiser le soutien politique au protectionnisme. Les int\u00e9r\u00eats particuliers parlent fort aux hommes politiques, alors que l&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral n&rsquo;est souvent pour eux qu&rsquo;un faible murmure. Toute politique est locale, s&rsquo;est exclam\u00e9 un jour Tip O&rsquo;Neill, leader de longue date de la Chambre des repr\u00e9sentants des \u00c9tats-Unis.         <\/p><div class='related_content'><span>RELATED<\/span><ul><li><a href='https:\/\/www.theconservative.online\/fr\/le-nouveau-bouclier-commercial-de-leurope-litalie-pousse-lue-a-defendre-lindustrie-contre-les-pressions-chinoises'>Le nouveau bouclier commercial de l&rsquo;Europe : L&rsquo;Italie pousse l&rsquo;UE \u00e0 d\u00e9fendre l&rsquo;industrie contre les pressions chinoises<\/li><\/a><li><a href='https:\/\/www.theconservative.online\/fr\/lettre-de-katowice'>Lettre de Katowice<\/li><\/a><li><a href='https:\/\/www.theconservative.online\/fr\/laccord-turnberry-et-la-fragilite-des-relations-transatlantiques-le-role-strategique-de-lunion-europeenne'>L&rsquo;accord Turnberry et la fragilit\u00e9 des relations transatlantiques : Le r\u00f4le strat\u00e9gique de l&rsquo;Union europ\u00e9enne<\/li><\/a><\/ul><\/div>\n<h3 style=\"font-weight: 400;\">Arguments plausibles mais fallacieux<\/h3>\n<p style=\"font-weight: 400;\">Le deuxi\u00e8me fait expliquant le soutien au protectionnisme est que de nombreux arguments en sa faveur semblent plausibles \u00e0 premi\u00e8re vue, m\u00eame s&rsquo;ils sont fallacieux. On dit que le libre-\u00e9change fait des gagnants et des perdants. Mais ses avantages l&#8217;emportent largement sur ses co\u00fbts, et les perdants ne le seront qu&rsquo;\u00e0 court terme. S&rsquo;il est vrai que la mar\u00e9e montante ne soul\u00e8ve pas tous les bateaux, il est tout aussi vrai qu&rsquo;aucun bateau n&rsquo;est soulev\u00e9 dans un mar\u00e9cage stagnant. On dit qu&rsquo;il faut prot\u00e9ger les emplois. Mais il y a beaucoup plus d&#8217;emplois cr\u00e9\u00e9s par l&rsquo;augmentation de la productivit\u00e9 que d&#8217;emplois perdus \u00e0 cause du libre-\u00e9change. On dit qu&rsquo;il faut prot\u00e9ger les salaires contre la sous-ench\u00e8re dans les pays \u00e0 bas salaires. Mais l\u00e0 encore, la cr\u00e9ation de richesses par l&rsquo;esprit d&rsquo;entreprise et l&rsquo;innovation sur des march\u00e9s internationaux comp\u00e9titifs augmentera la demande de main-d&rsquo;\u0153uvre et donc les salaires. On dit qu&rsquo;il faut prot\u00e9ger les industries naissantes. Mais quand l&rsquo;enfant devient-il un adulte qui n&rsquo;a plus besoin d&rsquo;\u00eatre prot\u00e9g\u00e9 de la concurrence \u00e9trang\u00e8re ?         <\/p>\n<h3 style=\"font-weight: 400;\">Arguments et alliances<\/h3>\n<p style=\"font-weight: 400;\">Bien s\u00fbr, si les \u00c9tats-Unis et l&rsquo;Union europ\u00e9enne adoptent le protectionnisme, ils sont suffisamment grands pour pouvoir n\u00e9anmoins b\u00e9n\u00e9ficier de la plupart des avantages de la division du travail et du libre-\u00e9change, puisque les \u00e9changes se feraient principalement entre les cinquante \u00c9tats membres des \u00c9tats-Unis et entre les vingt-sept \u00c9tats membres de l&rsquo;Union europ\u00e9enne, deux \u00e9normes march\u00e9s. Mais pour la plupart des autres pays, le protectionnisme se traduirait par de petites cours et de hautes cl\u00f4tures. Comment \u00e9viter cela ? En partie par des arguments, selon moi. Le protectionnisme doit et peut \u00eatre r\u00e9fut\u00e9, tandis que les opportunit\u00e9s cr\u00e9\u00e9es par le libre-\u00e9change doivent \u00eatre pr\u00e9sent\u00e9es avec force. C&rsquo;est ce que fait de mani\u00e8re convaincante une anthologie r\u00e9cente, <a href=\"https:\/\/www.amazon.co.uk\/Free-Trade-Twenty-First-Century-Political-ebook\/dp\/B0DF17CJMY\/ref=sr_1_1?crid=5OZNBHESILPJ&amp;dib=eyJ2IjoiMSJ9.NSEyxzFWkOx9yt3NqAirhA.hGRZwF8XEVYF8yrOhUoUDqR0TrugoC5mw6b80pLI9T0&amp;dib_tag=se&amp;keywords=hannan+rangeley+free+trade&amp;qid=1759498477&amp;sprefix=hannan+rangeley+free+trade%2Caps%2C293&amp;sr=8-1\"><em>Le libre-\u00e9change au XXIe si\u00e8cle<\/em><\/a>\u00e9dit\u00e9e par Lord <a href=\"https:\/\/danielhannan.info\">Daniel Hannan<\/a> et <a href=\"https:\/\/www.cobdencentre.org\/author\/max\/\">Max Rangeley<\/a>. En partie, je dirais que le protectionnisme pourrait \u00e9galement \u00eatre vaincu par des alliances de libre-\u00e9change, non seulement par des groupes de pression mais aussi par des soci\u00e9t\u00e9s d&rsquo;id\u00e9alistes, telles que l&rsquo;Anti-Corn Law League de Richard Cobden, dont la r\u00e9union de 1846 \u00e0 Exeter Hall, \u00e0 Londres, est illustr\u00e9e ci-dessus.      <\/p>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>S&rsquo;il est un principe sur lequel tous les \u00e9tudiants s\u00e9rieux en \u00e9conomie s&rsquo;accordent, c&rsquo;est bien celui du libre-\u00e9change. La division du travail entre les individus et les pays augmente le produit total, car les gens font alors ce qu&rsquo;ils savent faire le mieux, et ils en profitent, ainsi que les autres. Nous ne devons cependant [&hellip;]<\/p>\n","protected":false},"author":83,"featured_media":50963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2546,2575],"tags":[2977,2973,2976,2053,1155],"editorial-positions":[],"regions":[2566,2567,2568],"types":[2570],"class_list":["post-51651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essais","category-le-monde","tag-cobden","tag-hannan","tag-politicians","tag-protectionism","tag-trade","regions-usa-fr","regions-western-europe-fr","regions-world-fr","types-opinion-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un monde de petites cours et de hautes cl\u00f4tures ? Non ! - The Conservative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un monde de petites cours et de hautes cl\u00f4tures ? Non ! - The Conservative\" \/>\n<meta property=\"og:description\" content=\"S&rsquo;il est un principe sur lequel tous les \u00e9tudiants s\u00e9rieux en \u00e9conomie s&rsquo;accordent, c&rsquo;est bien celui du libre-\u00e9change. La division du travail entre les individus et les pays augmente le produit total, car les gens font alors ce qu&rsquo;ils savent faire le mieux, et ils en profitent, ainsi que les autres. Nous ne devons cependant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non\" \/>\n<meta property=\"og:site_name\" content=\"The Conservative\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hannes.h.gissurarson\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T19:09:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2026\/02\/1846_-_Anti-Corn_Law_League_Meeting.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hannes Gissurarson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HHGConferences\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hannes Gissurarson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non\"},\"author\":{\"name\":\"Hannes Gissurarson\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr#\\\/schema\\\/person\\\/57f9ac02d26987135183ffc3b91f4fbe\"},\"headline\":\"Un monde de petites cours et de hautes cl\u00f4tures ? Non !\",\"datePublished\":\"2026-02-28T19:09:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non\"},\"wordCount\":810,\"image\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theconservative.online\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1846_-_Anti-Corn_Law_League_Meeting.jpg\",\"keywords\":[\"Cobden\",\"Hannan\",\"Politicians\",\"protectionism\",\"trade\"],\"articleSection\":[\"Essais\",\"Le monde\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non\",\"url\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non\",\"name\":\"Un monde de petites cours et de hautes cl\u00f4tures ? Non ! - The Conservative\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theconservative.online\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1846_-_Anti-Corn_Law_League_Meeting.jpg\",\"datePublished\":\"2026-02-28T19:09:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr#\\\/schema\\\/person\\\/57f9ac02d26987135183ffc3b91f4fbe\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage\",\"url\":\"https:\\\/\\\/www.theconservative.online\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1846_-_Anti-Corn_Law_League_Meeting.jpg\",\"contentUrl\":\"https:\\\/\\\/www.theconservative.online\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1846_-_Anti-Corn_Law_League_Meeting.jpg\",\"width\":870,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/un-monde-de-petites-cours-et-de-hautes-clotures-non#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un monde de petites cours et de hautes cl\u00f4tures ? Non !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr#website\",\"url\":\"https:\\\/\\\/www.theconservative.online\\\/fr\",\"name\":\"The Conservative\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.theconservative.online\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.theconservative.online\\\/fr#\\\/schema\\\/person\\\/57f9ac02d26987135183ffc3b91f4fbe\",\"name\":\"Hannes Gissurarson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1292c6867aa2b48aaaf40f8359f130f8efbced45c7d0f5db3105feea926e93a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1292c6867aa2b48aaaf40f8359f130f8efbced45c7d0f5db3105feea926e93a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1292c6867aa2b48aaaf40f8359f130f8efbced45c7d0f5db3105feea926e93a?s=96&d=mm&r=g\",\"caption\":\"Hannes Gissurarson\"},\"description\":\"Born in 1953. D. Phil. Politics Oxford 1985. Professor of Politics 1988\u20132023. Professor Emeritus since 2023. Member of the Board of Directors Mont Pelerin Society 1998\u20132004. Member of the Board of Overseers Central Bank of Iceland 2001\u20132009. Visiting Scholar, Hoover Institution and many universities.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hannes.h.gissurarson\",\"https:\\\/\\\/www.instagram.com\\\/hannes1953\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/hannes-gissurarson-90485239\\\/\",\"https:\\\/\\\/x.com\\\/HHGConferences\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Hannes_H\u00f3lmsteinn_Gissurarson\"],\"url\":\"https:\\\/\\\/www.theconservative.online\\\/fr\\\/author\\\/hannes-euspec-2025-26\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un monde de petites cours et de hautes cl\u00f4tures ? Non ! - The Conservative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non","og_locale":"fr_FR","og_type":"article","og_title":"Un monde de petites cours et de hautes cl\u00f4tures ? Non ! - The Conservative","og_description":"S&rsquo;il est un principe sur lequel tous les \u00e9tudiants s\u00e9rieux en \u00e9conomie s&rsquo;accordent, c&rsquo;est bien celui du libre-\u00e9change. La division du travail entre les individus et les pays augmente le produit total, car les gens font alors ce qu&rsquo;ils savent faire le mieux, et ils en profitent, ainsi que les autres. Nous ne devons cependant [&hellip;]","og_url":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non","og_site_name":"The Conservative","article_author":"https:\/\/www.facebook.com\/hannes.h.gissurarson","article_published_time":"2026-02-28T19:09:35+00:00","og_image":[{"width":870,"height":711,"url":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2026\/02\/1846_-_Anti-Corn_Law_League_Meeting.jpg","type":"image\/jpeg"}],"author":"Hannes Gissurarson","twitter_card":"summary_large_image","twitter_creator":"@HHGConferences","twitter_misc":{"\u00c9crit par":"Hannes Gissurarson","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#article","isPartOf":{"@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non"},"author":{"name":"Hannes Gissurarson","@id":"https:\/\/www.theconservative.online\/fr#\/schema\/person\/57f9ac02d26987135183ffc3b91f4fbe"},"headline":"Un monde de petites cours et de hautes cl\u00f4tures ? Non !","datePublished":"2026-02-28T19:09:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non"},"wordCount":810,"image":{"@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage"},"thumbnailUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2026\/02\/1846_-_Anti-Corn_Law_League_Meeting.jpg","keywords":["Cobden","Hannan","Politicians","protectionism","trade"],"articleSection":["Essais","Le monde"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non","url":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non","name":"Un monde de petites cours et de hautes cl\u00f4tures ? Non ! - The Conservative","isPartOf":{"@id":"https:\/\/www.theconservative.online\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage"},"image":{"@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage"},"thumbnailUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2026\/02\/1846_-_Anti-Corn_Law_League_Meeting.jpg","datePublished":"2026-02-28T19:09:35+00:00","author":{"@id":"https:\/\/www.theconservative.online\/fr#\/schema\/person\/57f9ac02d26987135183ffc3b91f4fbe"},"breadcrumb":{"@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#primaryimage","url":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2026\/02\/1846_-_Anti-Corn_Law_League_Meeting.jpg","contentUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2026\/02\/1846_-_Anti-Corn_Law_League_Meeting.jpg","width":870,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/www.theconservative.online\/fr\/un-monde-de-petites-cours-et-de-hautes-clotures-non#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theconservative.online\/fr\/home"},{"@type":"ListItem","position":2,"name":"Un monde de petites cours et de hautes cl\u00f4tures ? Non !"}]},{"@type":"WebSite","@id":"https:\/\/www.theconservative.online\/fr#website","url":"https:\/\/www.theconservative.online\/fr","name":"The Conservative","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theconservative.online\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.theconservative.online\/fr#\/schema\/person\/57f9ac02d26987135183ffc3b91f4fbe","name":"Hannes Gissurarson","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d1292c6867aa2b48aaaf40f8359f130f8efbced45c7d0f5db3105feea926e93a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1292c6867aa2b48aaaf40f8359f130f8efbced45c7d0f5db3105feea926e93a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1292c6867aa2b48aaaf40f8359f130f8efbced45c7d0f5db3105feea926e93a?s=96&d=mm&r=g","caption":"Hannes Gissurarson"},"description":"Born in 1953. D. Phil. Politics Oxford 1985. Professor of Politics 1988\u20132023. Professor Emeritus since 2023. Member of the Board of Directors Mont Pelerin Society 1998\u20132004. Member of the Board of Overseers Central Bank of Iceland 2001\u20132009. Visiting Scholar, Hoover Institution and many universities.","sameAs":["https:\/\/www.facebook.com\/hannes.h.gissurarson","https:\/\/www.instagram.com\/hannes1953\/","https:\/\/www.linkedin.com\/in\/hannes-gissurarson-90485239\/","https:\/\/x.com\/HHGConferences","https:\/\/en.wikipedia.org\/wiki\/Hannes_H\u00f3lmsteinn_Gissurarson"],"url":"https:\/\/www.theconservative.online\/fr\/author\/hannes-euspec-2025-26"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/posts\/51651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/comments?post=51651"}],"version-history":[{"count":0,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/posts\/51651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/media\/50963"}],"wp:attachment":[{"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/media?parent=51651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/categories?post=51651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/tags?post=51651"},{"taxonomy":"editorial-positions","embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/editorial-positions?post=51651"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/regions?post=51651"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.theconservative.online\/fr\/wp-json\/wp\/v2\/types?post=51651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}