{"id":16358,"date":"2023-11-27T18:02:07","date_gmt":"2023-11-27T18:02:07","guid":{"rendered":"https:\/\/www.theconservative.online\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp"},"modified":"2023-11-27T18:02:07","modified_gmt":"2023-11-27T18:02:07","slug":"tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp","status":"publish","type":"post","link":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp","title":{"rendered":"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP"},"content":{"rendered":"<p>Illustri ospiti si sono riuniti venerd\u00ec 24 novembre nella prestigiosa Sala Koch del Senato della Repubblica in occasione della presentazione della Relazione annuale della Corte dei conti europea sull&#8217;esercizio finanziario 2022.<\/p>\n<p>Un evento fortemente voluto dal deputato alla Camera e segretario generale dell&#8217;ECR Antonio Giordano. Ha aperto la giornata presentando gli ospiti del panel e riassumendo le funzioni della Corte dei conti europea. On. Giordano ha pi\u00f9 volte ribadito il principio di sussidiariet\u00e0, definito come quel limite al di sotto del quale \u00e8 opportuno che lo Stato nazionale sia responsabile, in modo da impedire all&#8217;Unione Europea di legiferare anche sulle realt\u00e0 pi\u00f9 piccole.<\/p><div class='related_content'><span>RELATED<\/span><ul><li><a href='https:\/\/www.theconservative.online\/it\/studio-ecr-garantire-lapprovvigionamento-ripensare-lenergia-in-uneuropa-che-cambia'>Studio ECR: Garantire l&#8217;approvvigionamento &#8211; Ripensare l&#8217;energia in un&#8217;Europa che cambia<\/li><\/a><li><a href='https:\/\/www.theconservative.online\/it\/sondaggio-ecr-difesa-e-spesa-militare-in-europa'>Sondaggio ECR: Difesa e spesa militare in Europa<\/li><\/a><li><a href='https:\/\/www.theconservative.online\/it\/il-futuro-delleuropa-attraverso-una-visione-conservatrice'>Il futuro dell&#8217;Europa attraverso una visione conservatrice<\/li><\/a><\/ul><\/div>\n<p>La conferenza \u00e8 proseguita con il Ministro per gli Affari Parlamentari Luca Ciriani, che ha sottolineato la necessit\u00e0 di una collaborazione tra la Corte dei Conti e le amministrazioni per tutelare la finanza pubblica e la legalit\u00e0.<\/p>\n<p>Per portare il pubblico in una dimensione europea, \u00e8 intervenuto Pietro Russo, membro italiano della Corte dei conti europea. Nel suo intervento tecnico ha evidenziato quanto sia complicato per ogni Stato riuscire a ottenere i fondi e quanto sia difficile riuscire a spenderli. Subito dopo \u00e8 intervenuta l&#8217;europarlamentare Caterina Chinnici, membro del PPE e ora vicepresidente della Commissione per il controllo dei bilanci. Si \u00e8 soffermata in particolare sull&#8217;importanza vitale dei fondi del RRNP per valorizzare e sostenere l&#8217;intero territorio. Si tratta di un aspetto piuttosto delicato, perch\u00e9 la burocrazia rischia di rallentare il processo di finanziamento. Allo stesso tempo, Chinnici ha rivendicato la buona azione italiana e il fatto che la collaborazione di questo Paese con le autorit\u00e0 europee sta rendendo possibile il raggiungimento di una serie di obiettivi. Proprio in questi giorni, inoltre, la Commissione europea ha accolto la richiesta di emendamenti del governo Meloni. A differenza di quanto sostenuto da un certo giornalismo di sinistra, s\u00ec, \u00e8 possibile cambiare la RRNP. Ovviamente con un piano preciso e cambiamenti concreti per il Paese. In altre parole, quello che hanno fatto il Presidente del Consiglio Giorgia Meloni e il Ministro Raffaele Fitto.<\/p>\n<p>Illuminante anche l&#8217;intervento del Segretario Generale della Corte dei Conti italiana, Franco Massi. Tra i vari argomenti trattati da quest&#8217;ultimo, l&#8217;aspetto chiave \u00e8 stato la tempestivit\u00e0. Se il governo non agisce tempestivamente, anche gli investimenti pubblici possono diventare inutili in un tempo molto pi\u00f9 breve di quanto si possa immaginare. Sulla stessa lunghezza d&#8217;onda il Direttore della Struttura di Missione del RRNP, Alberto Manfredi Selvaggi, che ha spiegato come \u00e8 cambiato il mondo da quando sono stati stanziati i fondi per la Next Generation EU. Ha spiegato come i conflitti e le guerre rendano pi\u00f9 difficile e complicata l&#8217;azione dell&#8217;Unione Europea. Allo stesso tempo, per\u00f2, il principio rimane lo stesso: il denaro fornito non deve essere speso, ma deve essere utilizzato per raggiungere gli obiettivi. Un&#8217;apparente ovviet\u00e0 che per\u00f2 nasconde una verit\u00e0 che deve guidare l&#8217;azione del governo: non sprecare denaro in alcun modo, in gioco c&#8217;\u00e8 il futuro della nazione.<\/p>\n<p>Successivamente \u00e8 seguita una serie di interventi pi\u00f9 politici e meno tecnici. Sono intervenuti il Presidente della Commissione Finanze Marco Osnato e il Sottosegretario del Ministero dell&#8217;Economia e delle Finanze Lucia Albano. A questa seconda sessione ha partecipato anche il professor Luciano Monti dell&#8217;Osservatorio sulle politiche della Luiss. Anche in questo caso, abbiamo parlato di obiettivi da raggiungere, fondi da spendere nel miglior modo possibile e tempestivit\u00e0.<\/p>\n<p>La conferenza \u00e8 stata conclusa e riassunta dal Direttore dell&#8217;Osservatorio Politico della LUISS, Dr. Domenico Lombardi, che ha spiegato l&#8217;obiettivo della giornata: &#8220;Creare una piattaforma di dialogo tra funzionari governativi, parlamentari di spicco e membri delle principali strutture di controllo&#8221;. Ci\u00f2 che sorprende \u00e8 la grande convergenza tra tutti coloro che sono intervenuti. Ad esempio, il fatto che le irregolarit\u00e0 rappresentano costi che hanno comunque un impatto sulla societ\u00e0. &#8220;Un&#8217;altra voce di costo, parlando da economista, \u00e8 stata sottolineata dal presidente Osnato e dai vertici della Corte dei Conti, e si chiama comportamento difensivo nella pubblica amministrazione&#8221;, ha detto il direttore Lombardi. Questo comportamento comporta ovviamente una mancanza di tempestivit\u00e0. Per questo \u00e8 necessario impostare il lavoro delle strutture di revisione e della pubblica amministrazione secondo un principio di &#8220;leale collaborazione&#8221;. Questo incoraggerebbe anche una forma di apprendimento, in modo che coloro che conoscono meno la materia ma ricoprono cariche pubbliche non commettano errori involontari.<\/p>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Illustri ospiti si sono riuniti venerd\u00ec 24 novembre nella prestigiosa Sala Koch del Senato della Repubblica in occasione della presentazione della Relazione annuale della Corte dei conti europea sull&#8217;esercizio finanziario 2022. Un evento fortemente voluto dal deputato alla Camera e segretario generale dell&#8217;ECR Antonio Giordano. Ha aperto la giornata presentando gli ospiti del panel e [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":16227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153],"tags":[545,475],"editorial-positions":[42],"regions":[349],"types":[420],"class_list":["post-16358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-commercio-ed-economia","tag-ecr-party","tag-pnrr","editorial-positions-focus","regions-southern-europe-it","types-news-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP - The Conservative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP - The Conservative\" \/>\n<meta property=\"og:description\" content=\"Illustri ospiti si sono riuniti venerd\u00ec 24 novembre nella prestigiosa Sala Koch del Senato della Repubblica in occasione della presentazione della Relazione annuale della Corte dei conti europea sull&#8217;esercizio finanziario 2022. Un evento fortemente voluto dal deputato alla Camera e segretario generale dell&#8217;ECR Antonio Giordano. Ha aperto la giornata presentando gli ospiti del panel e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\" \/>\n<meta property=\"og:site_name\" content=\"The Conservative\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T18:02:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alessandro Imperiali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessandro Imperiali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\"},\"author\":{\"name\":\"Alessandro Imperiali\",\"@id\":\"https:\/\/www.theconservative.online\/it#\/schema\/person\/ec5124c7465d95b1145434fd45a67e41\"},\"headline\":\"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP\",\"datePublished\":\"2023-11-27T18:02:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\"},\"wordCount\":718,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg\",\"keywords\":[\"ECR Party\",\"PNRR\"],\"articleSection\":[\"Commercio ed Economia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\",\"url\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\",\"name\":\"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP - The Conservative\",\"isPartOf\":{\"@id\":\"https:\/\/www.theconservative.online\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg\",\"datePublished\":\"2023-11-27T18:02:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.theconservative.online\/it#\/schema\/person\/ec5124c7465d95b1145434fd45a67e41\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage\",\"url\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg\",\"contentUrl\":\"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg\",\"width\":1024,\"height\":682,\"caption\":\"Minister for Relations with Parliament Luca Ciriani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.theconservative.online\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.theconservative.online\/it#website\",\"url\":\"https:\/\/www.theconservative.online\/it\",\"name\":\"The Conservative\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.theconservative.online\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.theconservative.online\/it#\/schema\/person\/ec5124c7465d95b1145434fd45a67e41\",\"name\":\"Alessandro Imperiali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.theconservative.online\/it#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a9cc8d83038211eb892aa5524e3db0ce40b0c07efcfb877a2a8bb07f9f7d8c40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a9cc8d83038211eb892aa5524e3db0ce40b0c07efcfb877a2a8bb07f9f7d8c40?s=96&d=mm&r=g\",\"caption\":\"Alessandro Imperiali\"},\"url\":\"https:\/\/www.theconservative.online\/it\/author\/imperiali-euaff\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP - The Conservative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp","og_locale":"it_IT","og_type":"article","og_title":"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP - The Conservative","og_description":"Illustri ospiti si sono riuniti venerd\u00ec 24 novembre nella prestigiosa Sala Koch del Senato della Repubblica in occasione della presentazione della Relazione annuale della Corte dei conti europea sull&#8217;esercizio finanziario 2022. Un evento fortemente voluto dal deputato alla Camera e segretario generale dell&#8217;ECR Antonio Giordano. Ha aperto la giornata presentando gli ospiti del panel e [&hellip;]","og_url":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp","og_site_name":"The Conservative","article_published_time":"2023-11-27T18:02:07+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg","type":"image\/jpeg"}],"author":"Alessandro Imperiali","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Alessandro Imperiali","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#article","isPartOf":{"@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp"},"author":{"name":"Alessandro Imperiali","@id":"https:\/\/www.theconservative.online\/it#\/schema\/person\/ec5124c7465d95b1145434fd45a67e41"},"headline":"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP","datePublished":"2023-11-27T18:02:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp"},"wordCount":718,"commentCount":0,"image":{"@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage"},"thumbnailUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg","keywords":["ECR Party","PNRR"],"articleSection":["Commercio ed Economia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp","url":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp","name":"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP - The Conservative","isPartOf":{"@id":"https:\/\/www.theconservative.online\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage"},"image":{"@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage"},"thumbnailUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg","datePublished":"2023-11-27T18:02:07+00:00","author":{"@id":"https:\/\/www.theconservative.online\/it#\/schema\/person\/ec5124c7465d95b1145434fd45a67e41"},"breadcrumb":{"@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#primaryimage","url":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg","contentUrl":"https:\/\/www.theconservative.online\/wp-content\/uploads\/2023\/11\/ministro-ciriani.jpg","width":1024,"height":682,"caption":"Minister for Relations with Parliament Luca Ciriani"},{"@type":"BreadcrumbList","@id":"https:\/\/www.theconservative.online\/it\/tempestivita-sussidiarieta-e-responsabilita-parole-chiave-del-rrnp#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theconservative.online\/it"},{"@type":"ListItem","position":2,"name":"Tempestivit\u00e0, sussidiariet\u00e0 e responsabilit\u00e0: Parole chiave del RRNP"}]},{"@type":"WebSite","@id":"https:\/\/www.theconservative.online\/it#website","url":"https:\/\/www.theconservative.online\/it","name":"The Conservative","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theconservative.online\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.theconservative.online\/it#\/schema\/person\/ec5124c7465d95b1145434fd45a67e41","name":"Alessandro Imperiali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.theconservative.online\/it#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a9cc8d83038211eb892aa5524e3db0ce40b0c07efcfb877a2a8bb07f9f7d8c40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9cc8d83038211eb892aa5524e3db0ce40b0c07efcfb877a2a8bb07f9f7d8c40?s=96&d=mm&r=g","caption":"Alessandro Imperiali"},"url":"https:\/\/www.theconservative.online\/it\/author\/imperiali-euaff"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/posts\/16358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/comments?post=16358"}],"version-history":[{"count":0,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/posts\/16358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/media\/16227"}],"wp:attachment":[{"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/media?parent=16358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/categories?post=16358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/tags?post=16358"},{"taxonomy":"editorial-positions","embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/editorial-positions?post=16358"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/regions?post=16358"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.theconservative.online\/it\/wp-json\/wp\/v2\/types?post=16358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}